{"id":9954,"date":"2019-01-18T11:02:06","date_gmt":"2019-01-18T11:02:06","guid":{"rendered":"http:\/\/4dhealth.com\/installacions\/"},"modified":"2022-07-11T10:00:20","modified_gmt":"2022-07-11T10:00:20","slug":"instalaciones","status":"publish","type":"page","link":"https:\/\/4dhealth.com\/es\/instalaciones\/","title":{"rendered":"Instalaciones"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"9954\" class=\"elementor elementor-9954 elementor-9658 elementor-bc-flex-widget\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b6d2a08 elementor-section-stretched elementor-section-full_width elementor-section-height-min-height elementor-section-content-middle elementor-section-height-default elementor-section-items-middle\" data-id=\"b6d2a08\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1960fda\" data-id=\"1960fda\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a8ad200 elementor-widget elementor-widget-text-editor\" data-id=\"a8ad200\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3><span style=\"color: #ffffff;\">Ofrece una gran variedad de espacio\u00a0<\/span><\/h3><h3><span style=\"color: #ffffff;\">cl\u00ednicos y no cl\u00ednicos<\/span><\/h3>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3205941 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3205941\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7dab7ea\" data-id=\"7dab7ea\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9751a9e elementor-align-right elementor-widget elementor-widget-button\" data-id=\"9751a9e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/virtea.com\/tours\/784\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">\u2192\u00a0Visita virtual<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b2c1977 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b2c1977\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9692927\" data-id=\"9692927\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bef70a6 elementor-widget elementor-widget-text-editor\" data-id=\"bef70a6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #000000; background-image: initial; background-position: initial; background-size: initial; background-repeat: initial; background-attachment: initial; background-origin: initial; background-clip: initial;\">4D Health dispone de 2.500m<sup>2\u00a0<\/sup>distribuidos en 3 plantas, que incluye pasillos, salas de espera y ascensores.\u00a0<\/span><span style=\"color: #000000; background-image: initial; background-position: initial; background-size: initial; background-repeat: initial; background-attachment: initial; background-origin: initial; background-clip: initial;\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-9689 alignright\" src=\"http:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/Edifici4DH-300x169.png\" alt=\"\" width=\"324\" height=\"183\" srcset=\"https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/Edifici4DH-300x169.png 300w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/Edifici4DH-158x88.png 158w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/Edifici4DH-418x235.png 418w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/Edifici4DH.png 628w\" sizes=\"(max-width: 324px) 100vw, 324px\" \/><\/span><\/p><ul><li><span style=\"color: #000000;\"><b style=\"text-indent: 36pt;\"><b>Espacios cl\u00ednicos:<\/b><\/b><\/span><span style=\"letter-spacing: 0px;\"><span style=\"letter-spacing: 0px;\">\u00a0farmacia hospitalaria, \u00e1rea de urgencias, emergencias extrahospitalarias, piso adaptado, consultas externas, atenci\u00f3n primaria, \u00e1rea quir\u00fargica (quir\u00f3fanos, \u00e1rea de reanimaci\u00f3n, lavado quir\u00fargico y sala de informaci\u00f3n) y \u00e1rea de hospitalizaci\u00f3n (habitaciones individuales y dobles , control de enfermer\u00eda y sala de medicaci\u00f3n)<br \/><\/span><\/span><\/li><li><span style=\"color: #000000;\"><b style=\"text-indent: 36pt;\">Otros espacios:<\/b><span style=\"text-indent: 36pt;\"> auditorio, vest\u00edbulo, producci\u00f3n audiovisual, aulas lectivas, salas de reuniones, vestuarios, camerino y patio exterior privado con un amplio parking.\u00a0<\/span><\/span><\/li><\/ul><p style=\"margin-top: .2pt;\"><span style=\"color: #000000; background-image: initial; background-position: initial; background-size: initial; background-repeat: initial; background-attachment: initial; background-origin: initial; background-clip: initial;\">Las\u00a0<\/span><span lang=\"es\">instalaciones cuentan con los equipamientos m\u00e9dicos correspondientes y sistemas audiovisuales que permiten ver y escuchar toda actividad en el centro. Disponemos de un equipo de extras y profesionales sanitarios, adem\u00e1s de personal de producci\u00f3n para ayudar en tareas t\u00e9cnicas.<\/span><b><\/b><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ab233ae elementor-widget elementor-widget-video\" data-id=\"ab233ae\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;video_type&quot;:&quot;vimeo&quot;,&quot;start&quot;:0}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<iframe class=\"elementor-video-iframe\" allowfullscreen allow=\"clipboard-write\" title=\"Reproductor de v\u00eddeo vimeo\" src=\"https:\/\/player.vimeo.com\/video\/75380576?color&amp;autopause=0&amp;loop=0&amp;muted=0&amp;title=0&amp;portrait=1&amp;byline=0#t=\"><\/iframe>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ea52eb4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ea52eb4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-66cb45d\" data-id=\"66cb45d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-69ef46d elementor-widget elementor-widget-accordion\" data-id=\"69ef46d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1111\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1111\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Vest\u00edbulo<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1111\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1111\"><p><span lang=\"es\">El vest\u00edbulo es un espacio de recepci\u00f3n con luz natural, el cual se puede transformar en la entrada de un centro sanitario, espec\u00edficamente, en la zona de recepci\u00f3n y la sala de espera del \u00e1rea de urgencias del centro. A la vez, es un distribuidor hacia todos los otros espacios del centro.<\/span><\/p><p><img decoding=\"async\" class=\"alignnone wp-image-8888 size-medium\" src=\"http:\/\/4dhealth.com\/wp-content\/uploads\/2018\/12\/vestibul2-e1547811273893-300x194.jpg\" alt=\"\" width=\"300\" height=\"194\" srcset=\"https:\/\/4dhealth.com\/wp-content\/uploads\/2018\/12\/vestibul2-e1547811273893-300x194.jpg 300w, https:\/\/4dhealth.com\/wp-content\/uploads\/2018\/12\/vestibul2-e1547811273893-768x497.jpg 768w, https:\/\/4dhealth.com\/wp-content\/uploads\/2018\/12\/vestibul2-e1547811273893-418x270.jpg 418w, https:\/\/4dhealth.com\/wp-content\/uploads\/2018\/12\/vestibul2-e1547811273893.jpg 782w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img decoding=\"async\" class=\"alignnone wp-image-8882 size-medium\" src=\"http:\/\/4dhealth.com\/wp-content\/uploads\/2018\/12\/vestibul5-e1547811578978-300x195.jpg\" alt=\"\" width=\"300\" height=\"195\" \/>\u00a0<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-10159\" src=\"http:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/Hall-1a-planta-2-e1548948544956-300x194.jpg\" alt=\"\" width=\"300\" height=\"194\" srcset=\"https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/Hall-1a-planta-2-e1548948544956-300x194.jpg 300w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/Hall-1a-planta-2-e1548948544956.jpg 414w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p><p>\u00a0<img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-10825 size-medium\" src=\"https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/07\/IMG_5808-e1563373448878-300x190.jpg\" alt=\"\" width=\"300\" height=\"190\" srcset=\"https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/07\/IMG_5808-e1563373448878-300x190.jpg 300w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/07\/IMG_5808-e1563373448878-768x487.jpg 768w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/07\/IMG_5808-e1563373448878-1024x649.jpg 1024w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/07\/IMG_5808-e1563373448878-418x265.jpg 418w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\u00a0<img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-10829 size-medium\" src=\"https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/07\/IMG_5810-e1563373500891-300x190.jpg\" alt=\"\" width=\"300\" height=\"190\" srcset=\"https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/07\/IMG_5810-e1563373500891-300x190.jpg 300w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/07\/IMG_5810-e1563373500891-768x486.jpg 768w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/07\/IMG_5810-e1563373500891-1024x648.jpg 1024w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/07\/IMG_5810-e1563373500891-418x264.jpg 418w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p><p>Superficie: 111m\u00b2<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1112\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-1112\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Auditorio<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1112\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-1112\"><p><span lang=\"es\">El auditorio del 4D Health es un espacio de 80m\u00b2 con aforo para 65 personas, ampliable a 100 m\u00b2 y un aforo hasta 100 personas, que integra una tecnolog\u00eda audiovisual la que permite la visualizaci\u00f3n a doble pantalla de las actividades en los diferentes espacios del centro en tiempo real o en diferido. Dispone de un espacio destinado para el control de los sistemas audiovisuales.<\/span><\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-9266 size-medium\" src=\"http:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/20180709_165648-e1547812625958-300x197.jpg\" alt=\"\" width=\"300\" height=\"197\" srcset=\"https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/20180709_165648-e1547812625958-300x197.jpg 300w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/20180709_165648-e1547812625958-768x504.jpg 768w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/20180709_165648-e1547812625958-1024x672.jpg 1024w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/20180709_165648-e1547812625958-418x274.jpg 418w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-9269 size-medium\" src=\"http:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/Auditori7-e1547812752377-300x194.jpg\" alt=\"\" width=\"300\" height=\"194\" srcset=\"https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/Auditori7-e1547812752377-300x194.jpg 300w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/Auditori7-e1547812752377-768x496.jpg 768w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/Auditori7-e1547812752377-418x270.jpg 418w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/Auditori7-e1547812752377.jpg 874w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\u00a0<img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-10224 size-medium\" src=\"http:\/\/4dhealth.com\/wp-content\/uploads\/2019\/02\/IMG_10321-e1549294174693-300x194.jpg\" alt=\"\" width=\"300\" height=\"194\" srcset=\"https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/02\/IMG_10321-e1549294174693-300x194.jpg 300w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/02\/IMG_10321-e1549294174693-768x496.jpg 768w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/02\/IMG_10321-e1549294174693-1024x661.jpg 1024w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/02\/IMG_10321-e1549294174693-418x270.jpg 418w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p><p>Superficie: 100m\u00b2<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1113\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-1113\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Sala de Producci\u00f3n Audiovisual<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1113\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-1113\"><p><span lang=\"es\">Espacio destinado al control del sistema audiovisual incorporado al centro, permiten la observaci\u00f3n, evaluaci\u00f3n y grabaci\u00f3n continua en directo de los escenarios. Nuestro equipo incluye c\u00e1maras digitales robotizadas con zoom y equipos de audio de alta calidad.<\/span><\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-9275\" src=\"http:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/Control10-1-300x168.jpg\" alt=\"\" width=\"300\" height=\"168\" srcset=\"https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/Control10-1-300x168.jpg 300w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/Control10-1-768x430.jpg 768w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/Control10-1-158x88.jpg 158w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/Control10-1-418x234.jpg 418w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/Control10-1.jpg 960w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-9278\" src=\"http:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/Control8-300x168.jpg\" alt=\"\" width=\"300\" height=\"168\" srcset=\"https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/Control8-300x168.jpg 300w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/Control8-768x430.jpg 768w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/Control8-158x88.jpg 158w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/Control8-418x234.jpg 418w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/Control8.jpg 960w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\u00a0<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-9662\" src=\"http:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/Control2-300x168.jpg\" alt=\"\" width=\"300\" height=\"168\" srcset=\"https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/Control2-300x168.jpg 300w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/Control2-158x88.jpg 158w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/Control2-418x235.jpg 418w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/Control2.jpg 647w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1114\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-1114\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Farmacia Hospitalaria y Comunitaria<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1114\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-1114\"><p><span lang=\"es\">Farmacia hospitalaria con la tecnolog\u00eda y los circuitos para el almacenamiento (Kardex de Grifols) y dispensaci\u00f3n de medicamentos tanto a nivel hospitalario como comunitario. Disponemos tambi\u00e9n de una campana de flujo vertical para la preparaci\u00f3n de f\u00e1rmacos peligrosos.<\/span><\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-7973 size-medium\" src=\"http:\/\/4dhealth.com\/wp-content\/uploads\/2018\/11\/farmacia-e1548948861801-300x197.jpg\" alt=\"\" width=\"300\" height=\"197\" srcset=\"https:\/\/4dhealth.com\/wp-content\/uploads\/2018\/11\/farmacia-e1548948861801-300x197.jpg 300w, https:\/\/4dhealth.com\/wp-content\/uploads\/2018\/11\/farmacia-e1548948861801-418x275.jpg 418w, https:\/\/4dhealth.com\/wp-content\/uploads\/2018\/11\/farmacia-e1548948861801.jpg 465w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\u00a0\u00a0<img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-9665 size-medium\" style=\"font-size: 1rem; letter-spacing: 0px;\" src=\"http:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/Farm\u00e0cia2-e1548949646166-300x198.jpg\" alt=\"\" width=\"300\" height=\"198\" srcset=\"https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/Farm\u00e0cia2-e1548949646166-300x198.jpg 300w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/Farm\u00e0cia2-e1548949646166-418x276.jpg 418w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/Farm\u00e0cia2-e1548949646166.jpg 576w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\u00a0\u00a0<img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-10163 size-medium\" src=\"http:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/2015-03-19-PB-FARM\u00c0CIA-6-e1548949008601-300x198.jpg\" alt=\"\" width=\"300\" height=\"198\" srcset=\"https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/2015-03-19-PB-FARM\u00c0CIA-6-e1548949008601-300x198.jpg 300w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/2015-03-19-PB-FARM\u00c0CIA-6-e1548949008601-768x507.jpg 768w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/2015-03-19-PB-FARM\u00c0CIA-6-e1548949008601-418x276.jpg 418w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/2015-03-19-PB-FARM\u00c0CIA-6-e1548949008601.jpg 990w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p><p>Superficie: 36,48m\u00b2<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1115\" class=\"elementor-tab-title\" data-tab=\"5\" role=\"button\" aria-controls=\"elementor-tab-content-1115\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">\u00c1rea de urgencias<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1115\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"5\" role=\"region\" aria-labelledby=\"elementor-tab-title-1115\"><p><span lang=\"es\">Ofrece espacios desde la atenci\u00f3n del paciente en la sala de espera, zona de triaje, zona de atenci\u00f3n a pacientes cr\u00edticos, la posibilidad de transferencia de pacientes a cualquier \u00e1rea hospitalaria mediante pasillos y ascensor, y llegada de pacientes con transporte sanitario por formaciones extra hospitalarias. Incluye gases m\u00e9dicos, equipamientos m\u00e9dicos habituales del \u00e1rea de urgencias y una Pyxis.<\/span><\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-8885\" src=\"http:\/\/4dhealth.com\/wp-content\/uploads\/2018\/12\/vestibul1-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/4dhealth.com\/wp-content\/uploads\/2018\/12\/vestibul1-300x200.jpg 300w, https:\/\/4dhealth.com\/wp-content\/uploads\/2018\/12\/vestibul1-768x512.jpg 768w, https:\/\/4dhealth.com\/wp-content\/uploads\/2018\/12\/vestibul1-418x279.jpg 418w, https:\/\/4dhealth.com\/wp-content\/uploads\/2018\/12\/vestibul1.jpg 783w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-8909\" src=\"http:\/\/4dhealth.com\/wp-content\/uploads\/2018\/12\/area-urgencies4-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/4dhealth.com\/wp-content\/uploads\/2018\/12\/area-urgencies4-300x200.jpg 300w, https:\/\/4dhealth.com\/wp-content\/uploads\/2018\/12\/area-urgencies4-768x511.jpg 768w, https:\/\/4dhealth.com\/wp-content\/uploads\/2018\/12\/area-urgencies4-418x278.jpg 418w, https:\/\/4dhealth.com\/wp-content\/uploads\/2018\/12\/area-urgencies4.jpg 983w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\u00a0<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-9668\" src=\"http:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/2015-03-19-PB-BOX-TRIATGE-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/2015-03-19-PB-BOX-TRIATGE-300x200.jpg 300w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/2015-03-19-PB-BOX-TRIATGE-768x511.jpg 768w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/2015-03-19-PB-BOX-TRIATGE-1024x681.jpg 1024w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/2015-03-19-PB-BOX-TRIATGE-418x278.jpg 418w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/2015-03-19-PB-BOX-TRIATGE.jpg 1479w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-9671\" src=\"http:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/Hospitalitzaci\u00f36-300x195.jpg\" alt=\"\" width=\"300\" height=\"195\" srcset=\"https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/Hospitalitzaci\u00f36-300x195.jpg 300w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/Hospitalitzaci\u00f36-768x500.jpg 768w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/Hospitalitzaci\u00f36-418x272.jpg 418w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/Hospitalitzaci\u00f36.jpg 810w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-8915\" src=\"http:\/\/4dhealth.com\/wp-content\/uploads\/2018\/12\/area-urgencies6-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/4dhealth.com\/wp-content\/uploads\/2018\/12\/area-urgencies6-300x200.jpg 300w, https:\/\/4dhealth.com\/wp-content\/uploads\/2018\/12\/area-urgencies6-768x512.jpg 768w, https:\/\/4dhealth.com\/wp-content\/uploads\/2018\/12\/area-urgencies6-1024x683.jpg 1024w, https:\/\/4dhealth.com\/wp-content\/uploads\/2018\/12\/area-urgencies6-418x279.jpg 418w, https:\/\/4dhealth.com\/wp-content\/uploads\/2018\/12\/area-urgencies6.jpg 1040w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\u00a0<img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-9874 size-medium\" src=\"http:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/Urg\u00e8ncies8-e1548229885968-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/Urg\u00e8ncies8-e1548229885968-300x200.jpg 300w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/Urg\u00e8ncies8-e1548229885968-418x278.jpg 418w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/Urg\u00e8ncies8-e1548229885968.jpg 679w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p><p>Superficie: 75,19m\u00b2<\/p><p>Superficie extra hospitalaria: 100m\u00b2<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1116\" class=\"elementor-tab-title\" data-tab=\"6\" role=\"button\" aria-controls=\"elementor-tab-content-1116\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">\u00c1rea de atenci\u00f3n domiciliaria<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1116\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"6\" role=\"region\" aria-labelledby=\"elementor-tab-title-1116\"><p><span lang=\"es\">Disponemos de una vivienda equipada de una habitaci\u00f3n, con lavabo. Permite la valoraci\u00f3n y manejo de pacientes en el ambiente domiciliario.<\/span><\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-8921\" src=\"http:\/\/4dhealth.com\/wp-content\/uploads\/2018\/12\/area-atencio-domiciliaria2-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" \/>\u00a0<img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-8927 size-medium\" src=\"http:\/\/4dhealth.com\/wp-content\/uploads\/2018\/12\/area-atencio-domiciliaria4-e1547814924251-300x194.jpg\" alt=\"\" width=\"300\" height=\"194\" srcset=\"https:\/\/4dhealth.com\/wp-content\/uploads\/2018\/12\/area-atencio-domiciliaria4-e1547814924251-300x194.jpg 300w, https:\/\/4dhealth.com\/wp-content\/uploads\/2018\/12\/area-atencio-domiciliaria4-e1547814924251-418x270.jpg 418w, https:\/\/4dhealth.com\/wp-content\/uploads\/2018\/12\/area-atencio-domiciliaria4-e1547814924251.jpg 755w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\u00a0<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-8924\" src=\"http:\/\/4dhealth.com\/wp-content\/uploads\/2018\/12\/area-atencio-domiciliaria3-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/4dhealth.com\/wp-content\/uploads\/2018\/12\/area-atencio-domiciliaria3-300x200.jpg 300w, https:\/\/4dhealth.com\/wp-content\/uploads\/2018\/12\/area-atencio-domiciliaria3-768x511.jpg 768w, https:\/\/4dhealth.com\/wp-content\/uploads\/2018\/12\/area-atencio-domiciliaria3-418x278.jpg 418w, https:\/\/4dhealth.com\/wp-content\/uploads\/2018\/12\/area-atencio-domiciliaria3.jpg 850w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\u00a0<\/p><p>Superficie: 28,44m\u00b2<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1117\" class=\"elementor-tab-title\" data-tab=\"7\" role=\"button\" aria-controls=\"elementor-tab-content-1117\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">\u00c1rea de consultas externas hospitalarias y \/ o de atenci\u00f3n primaria<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1117\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"7\" role=\"region\" aria-labelledby=\"elementor-tab-title-1117\"><p><span lang=\"es\">El centro 4D Health dispone de un \u00e1rea de recepci\u00f3n, sala de espera y 5 consultas equipadas para la atenci\u00f3n de pacientes a nivel de atenci\u00f3n primaria.<\/span><\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-7979 size-medium\" src=\"http:\/\/4dhealth.com\/wp-content\/uploads\/2018\/11\/sala-consultes-e1548229958777-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/4dhealth.com\/wp-content\/uploads\/2018\/11\/sala-consultes-e1548229958777-300x200.jpg 300w, https:\/\/4dhealth.com\/wp-content\/uploads\/2018\/11\/sala-consultes-e1548229958777-418x278.jpg 418w, https:\/\/4dhealth.com\/wp-content\/uploads\/2018\/11\/sala-consultes-e1548229958777.jpg 461w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-10210\" src=\"http:\/\/4dhealth.com\/wp-content\/uploads\/2019\/02\/IMG_1030-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/02\/IMG_1030-300x200.jpg 300w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/02\/IMG_1030-768x512.jpg 768w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/02\/IMG_1030-1024x683.jpg 1024w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/02\/IMG_1030-418x279.jpg 418w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-9686 size-medium\" src=\"http:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/Consulta-e1548230084259-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/Consulta-e1548230084259-300x200.jpg 300w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/Consulta-e1548230084259-768x512.jpg 768w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/Consulta-e1548230084259-1024x683.jpg 1024w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/Consulta-e1548230084259-418x279.jpg 418w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/Consulta-e1548230084259.jpg 1248w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\u00a0<\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-10213 size-medium\" src=\"http:\/\/4dhealth.com\/wp-content\/uploads\/2019\/02\/20180711_105910-e1549292998604-300x199.jpg\" alt=\"\" width=\"300\" height=\"199\" srcset=\"https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/02\/20180711_105910-e1549292998604-300x199.jpg 300w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/02\/20180711_105910-e1549292998604-768x511.jpg 768w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/02\/20180711_105910-e1549292998604-1024x681.jpg 1024w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/02\/20180711_105910-e1549292998604-418x278.jpg 418w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\u00a0<img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-10219 size-medium\" src=\"http:\/\/4dhealth.com\/wp-content\/uploads\/2019\/02\/Consulta1-e1549293609282-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/02\/Consulta1-e1549293609282-300x200.jpg 300w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/02\/Consulta1-e1549293609282-768x511.jpg 768w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/02\/Consulta1-e1549293609282-418x278.jpg 418w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/02\/Consulta1-e1549293609282.jpg 898w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\u00a0<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-10216\" src=\"http:\/\/4dhealth.com\/wp-content\/uploads\/2019\/02\/2015-03-19-P1-ESOF\u00c0GICA-1-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/02\/2015-03-19-P1-ESOF\u00c0GICA-1-300x200.jpg 300w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/02\/2015-03-19-P1-ESOF\u00c0GICA-1-768x511.jpg 768w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/02\/2015-03-19-P1-ESOF\u00c0GICA-1-1024x681.jpg 1024w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/02\/2015-03-19-P1-ESOF\u00c0GICA-1-418x278.jpg 418w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/02\/2015-03-19-P1-ESOF\u00c0GICA-1.jpg 1479w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p><p>Superficie: 184m\u00b2<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1118\" class=\"elementor-tab-title\" data-tab=\"8\" role=\"button\" aria-controls=\"elementor-tab-content-1118\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">\u00c1rea de hospitalizaci\u00f3n<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1118\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"8\" role=\"region\" aria-labelledby=\"elementor-tab-title-1118\"><p><span lang=\"es\">El \u00e1rea de hospitalizaci\u00f3n incluye control de enfermer\u00eda, zona para preparaci\u00f3n de medicamentos, habitaciones dobles e individuales. Los espacios est\u00e1n suficientemente equipados para realizar cualquier actividad hospitalaria.<\/span><\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-9888 size-medium\" src=\"http:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/Sin-t\u00edtulo-1-3-e1548239325367-300x178.jpg\" alt=\"\" width=\"300\" height=\"178\" srcset=\"https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/Sin-t\u00edtulo-1-3-e1548239325367-300x178.jpg 300w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/Sin-t\u00edtulo-1-3-e1548239325367-768x456.jpg 768w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/Sin-t\u00edtulo-1-3-e1548239325367-1024x608.jpg 1024w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/Sin-t\u00edtulo-1-3-e1548239325367-418x248.jpg 418w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/Sin-t\u00edtulo-1-3-e1548239325367-770x460.jpg 770w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\u00a0<img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-8825 size-medium\" src=\"http:\/\/4dhealth.com\/wp-content\/uploads\/2018\/12\/hospitalitzacio-pacient-e1548236784315-300x178.jpg\" alt=\"\" width=\"300\" height=\"178\" \/>\u00a0<img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-9862 size-medium\" src=\"http:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/Hospitalitzaci\u00f3-Passad\u00eds-e1548236690430-300x178.jpg\" alt=\"\" width=\"300\" height=\"178\" srcset=\"https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/Hospitalitzaci\u00f3-Passad\u00eds-e1548236690430-300x178.jpg 300w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/Hospitalitzaci\u00f3-Passad\u00eds-e1548236690430-768x457.jpg 768w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/Hospitalitzaci\u00f3-Passad\u00eds-e1548236690430-1024x609.jpg 1024w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/Hospitalitzaci\u00f3-Passad\u00eds-e1548236690430-418x248.jpg 418w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/Hospitalitzaci\u00f3-Passad\u00eds-e1548236690430-770x460.jpg 770w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/Hospitalitzaci\u00f3-Passad\u00eds-e1548236690430.jpg 1270w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-9879 size-medium\" src=\"http:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/IMG_9645-e1548236937724-300x178.jpg\" alt=\"\" width=\"300\" height=\"178\" srcset=\"https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/IMG_9645-e1548236937724-300x178.jpg 300w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/IMG_9645-e1548236937724-768x456.jpg 768w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/IMG_9645-e1548236937724-1024x608.jpg 1024w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/IMG_9645-e1548236937724-418x248.jpg 418w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/IMG_9645-e1548236937724-770x460.jpg 770w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\u00a0<img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-9292 size-medium\" src=\"http:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/Hospitalitzaci\u00f310-e1548237103383-300x179.jpg\" alt=\"\" width=\"300\" height=\"179\" srcset=\"https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/Hospitalitzaci\u00f310-e1548237103383-300x179.jpg 300w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/Hospitalitzaci\u00f310-e1548237103383-768x457.jpg 768w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/Hospitalitzaci\u00f310-e1548237103383-1024x609.jpg 1024w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/Hospitalitzaci\u00f310-e1548237103383-418x249.jpg 418w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/Hospitalitzaci\u00f310-e1548237103383-770x460.jpg 770w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/Hospitalitzaci\u00f310-e1548237103383.jpg 1472w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\u00a0<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-13220\" src=\"https:\/\/4dhealth.com\/wp-content\/uploads\/2022\/07\/Habitaci\u00f3-300x175.jpg\" alt=\"\" width=\"300\" height=\"175\" srcset=\"https:\/\/4dhealth.com\/wp-content\/uploads\/2022\/07\/Habitaci\u00f3-300x175.jpg 300w, https:\/\/4dhealth.com\/wp-content\/uploads\/2022\/07\/Habitaci\u00f3-768x449.jpg 768w, https:\/\/4dhealth.com\/wp-content\/uploads\/2022\/07\/Habitaci\u00f3-1024x599.jpg 1024w, https:\/\/4dhealth.com\/wp-content\/uploads\/2022\/07\/Habitaci\u00f3-418x244.jpg 418w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p><p>Habitaci\u00f3n doble, superficie: 24,11m\u00b2<\/p><p>Habitaci\u00f3n individual, superficie: 15,08m\u00b2<\/p><p><strong>Superficie total: 128,43m\u00b2<\/strong><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1119\" class=\"elementor-tab-title\" data-tab=\"9\" role=\"button\" aria-controls=\"elementor-tab-content-1119\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">\u00c1rea quir\u00fargica<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1119\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"9\" role=\"region\" aria-labelledby=\"elementor-tab-title-1119\"><p><span lang=\"es\">El \u00e1rea quir\u00fargica incluye circuitos que se pueden encontrar en un quir\u00f3fano real. Desde la transferencia del paciente del exterior, los vestuarios por los profesionales, \u00e1rea de reanimaci\u00f3n preoperatoria y postoperatoria (con capacidad para 3 pacientes), zona de trabajo de enfermer\u00eda, zona de lavados de manos quir\u00fargico, dos quir\u00f3fanos, zona de esterilizaci\u00f3n y zona de comunicaci\u00f3n con los familiares.<\/span><\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-9695 size-medium\" src=\"http:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/Sin-t\u00edtulo-3-e1548235879305-300x179.jpg\" alt=\"\" width=\"300\" height=\"179\" \/>\u00a0 <img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-9698 size-medium\" src=\"http:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/Quirofan-e1548235437436-300x179.jpg\" alt=\"\" width=\"300\" height=\"179\" srcset=\"https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/Quirofan-e1548235437436-300x179.jpg 300w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/Quirofan-e1548235437436-768x457.jpg 768w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/Quirofan-e1548235437436-1024x610.jpg 1024w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/Quirofan-e1548235437436-418x249.jpg 418w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/Quirofan-e1548235437436-770x460.jpg 770w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/Quirofan-e1548235437436.jpg 1327w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\u00a0\u00a0<img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-9450 size-medium\" src=\"http:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/Transfer-e1548315430377-300x178.jpg\" alt=\"\" width=\"300\" height=\"178\" srcset=\"https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/Transfer-e1548315430377-300x178.jpg 300w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/Transfer-e1548315430377-768x456.jpg 768w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/Transfer-e1548315430377-418x248.jpg 418w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/Transfer-e1548315430377-770x460.jpg 770w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/Transfer-e1548315430377.jpg 932w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\u00a0<\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-9892\" src=\"http:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/IMG_20180706_105933-300x169.jpg\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/IMG_20180706_105933-300x169.jpg 300w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/IMG_20180706_105933-768x433.jpg 768w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/IMG_20180706_105933-1024x577.jpg 1024w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/IMG_20180706_105933-158x88.jpg 158w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/IMG_20180706_105933-418x236.jpg 418w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/IMG_20180706_105933-1920x1080.jpg 1920w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\u00a0 <img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-10149 size-medium\" src=\"http:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/2015-03-19-P1-QUIR\u00d2FAN-1-2-e1549290168412-300x169.jpg\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/2015-03-19-P1-QUIR\u00d2FAN-1-2-e1549290168412-300x169.jpg 300w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/2015-03-19-P1-QUIR\u00d2FAN-1-2-e1549290168412-768x432.jpg 768w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/2015-03-19-P1-QUIR\u00d2FAN-1-2-e1549290168412-1024x577.jpg 1024w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/2015-03-19-P1-QUIR\u00d2FAN-1-2-e1549290168412-158x88.jpg 158w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/2015-03-19-P1-QUIR\u00d2FAN-1-2-e1549290168412-418x235.jpg 418w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/2015-03-19-P1-QUIR\u00d2FAN-1-2-e1549290168412.jpg 1355w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\u00a0 <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-9899\" src=\"http:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/Quirofan5-300x169.jpg\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/Quirofan5-300x169.jpg 300w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/Quirofan5-768x432.jpg 768w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/Quirofan5-1024x576.jpg 1024w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/Quirofan5-158x88.jpg 158w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/Quirofan5-418x235.jpg 418w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/Quirofan5.jpg 1600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p><p>\u00c1rea reanimaci\u00f3n,\u00a0<span lang=\"es\">preanest\u00e9sica y postanest\u00e9sica, superficie<\/span>: 75,61m\u00b2<\/p><p>Sala comunicaci\u00f3n familiares, superficie: 9,06m\u00b2<\/p><p>Quir\u00f3fano 1, superficie: 46,12m\u00b2<\/p><p>Quir\u00f3fano 2, superficie: 31,27m\u00b2<\/p><p>Lavado de manos quir\u00fargico superficie: 14,09m\u00b2<\/p><p><strong>Superficie Total: 286,76m\u00b2<\/strong><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-11110\" class=\"elementor-tab-title\" data-tab=\"10\" role=\"button\" aria-controls=\"elementor-tab-content-11110\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Sala de reuniones<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-11110\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"10\" role=\"region\" aria-labelledby=\"elementor-tab-title-11110\"><p><span lang=\"es\">Disponemos de un espacio luz natural para hacer reuniones, trabajos en grupo, etc &#8230; equipado con equipos de proyecci\u00f3n que permiten la visualizaci\u00f3n en directo y diferido de actividades en cualquier parte del centro.<\/span><\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-9284 size-medium\" src=\"http:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/SalaReunions2-e1547816599317-300x218.jpg\" alt=\"\" width=\"300\" height=\"218\" srcset=\"https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/SalaReunions2-e1547816599317-300x218.jpg 300w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/SalaReunions2-e1547816599317-768x557.jpg 768w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/SalaReunions2-e1547816599317-1024x743.jpg 1024w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/SalaReunions2-e1547816599317-418x303.jpg 418w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-9281 size-medium\" src=\"http:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/SalaReunions-e1548236033457-300x218.jpg\" alt=\"\" width=\"300\" height=\"218\" srcset=\"https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/SalaReunions-e1548236033457-300x218.jpg 300w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/SalaReunions-e1548236033457-768x558.jpg 768w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/SalaReunions-e1548236033457-1024x744.jpg 1024w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/SalaReunions-e1548236033457-418x304.jpg 418w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p><p>Superficie: 29,62m\u00b2<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-11111\" class=\"elementor-tab-title\" data-tab=\"11\" role=\"button\" aria-controls=\"elementor-tab-content-11111\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Sala debriefing<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-11111\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"11\" role=\"region\" aria-labelledby=\"elementor-tab-title-11111\"><p><span lang=\"es\">Disponemos de un espacio para trabajos en grupo y debriefing equipado con equipos de proyecci\u00f3n que permiten la visualizaci\u00f3n en directo y diferido de actividades en cualquier parte del centro.<\/span><\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-9677\" src=\"http:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/Sala3-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/Sala3-300x200.jpg 300w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/Sala3-768x512.jpg 768w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/Sala3-418x279.jpg 418w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/Sala3.jpg 1008w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-9680 size-medium\" src=\"http:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/Sala-e1548236440847-300x199.jpg\" alt=\"\" width=\"300\" height=\"199\" srcset=\"https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/Sala-e1548236440847-300x199.jpg 300w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/Sala-e1548236440847-768x511.jpg 768w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/Sala-e1548236440847-418x278.jpg 418w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/01\/Sala-e1548236440847.jpg 782w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p><p>Superficie: 25m\u00b2<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-11112\" class=\"elementor-tab-title\" data-tab=\"12\" role=\"button\" aria-controls=\"elementor-tab-content-11112\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">\u00c1rea docencia<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-11112\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"12\" role=\"region\" aria-labelledby=\"elementor-tab-title-11112\"><p><span lang=\"es\">Disponemos de espacios equipados con mesas, sillas y equipos de proyecci\u00f3n para la realizaci\u00f3n de actividades formativas.<\/span><\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-10177\" src=\"http:\/\/4dhealth.com\/wp-content\/uploads\/2019\/02\/IMG_0992-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/02\/IMG_0992-300x200.jpg 300w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/02\/IMG_0992-768x512.jpg 768w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/02\/IMG_0992-1024x683.jpg 1024w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/02\/IMG_0992-418x279.jpg 418w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-10180\" src=\"http:\/\/4dhealth.com\/wp-content\/uploads\/2019\/02\/IMG_0995-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/02\/IMG_0995-300x200.jpg 300w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/02\/IMG_0995-768x512.jpg 768w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/02\/IMG_0995-1024x683.jpg 1024w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/02\/IMG_0995-418x279.jpg 418w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-10183\" src=\"http:\/\/4dhealth.com\/wp-content\/uploads\/2019\/02\/IMG_1009-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/02\/IMG_1009-300x200.jpg 300w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/02\/IMG_1009-768x512.jpg 768w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/02\/IMG_1009-1024x683.jpg 1024w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/02\/IMG_1009-418x279.jpg 418w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\u00a0<\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-10186\" src=\"http:\/\/4dhealth.com\/wp-content\/uploads\/2019\/02\/IMG_1010-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/02\/IMG_1010-300x200.jpg 300w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/02\/IMG_1010-768x512.jpg 768w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/02\/IMG_1010-1024x683.jpg 1024w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/02\/IMG_1010-418x279.jpg 418w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-10192\" src=\"http:\/\/4dhealth.com\/wp-content\/uploads\/2019\/02\/IMG_1013-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/02\/IMG_1013-300x200.jpg 300w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/02\/IMG_1013-768x512.jpg 768w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/02\/IMG_1013-1024x683.jpg 1024w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/02\/IMG_1013-418x279.jpg 418w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-10199\" src=\"http:\/\/4dhealth.com\/wp-content\/uploads\/2019\/02\/IMG_1004-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/02\/IMG_1004-300x200.jpg 300w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/02\/IMG_1004-768x512.jpg 768w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/02\/IMG_1004-1024x683.jpg 1024w, https:\/\/4dhealth.com\/wp-content\/uploads\/2019\/02\/IMG_1004-418x279.jpg 418w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3155879 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3155879\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-48bd3d9\" data-id=\"48bd3d9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1ddecdc elementor-align-right elementor-widget elementor-widget-button\" data-id=\"1ddecdc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/4dhealth.com\/wp-content\/uploads\/2020\/09\/4D-Health_Espacios_.pdf\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">DESCARGA PDF<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Ofrece una gran variedad de espacio\u00a0 cl\u00ednicos y no cl\u00ednicos \u2192\u00a0Visita virtual 4D Health dispone de 2.500m2\u00a0distribuidos en 3 plantas, que incluye pasillos, salas de espera y ascensores.\u00a0 Espacios cl\u00ednicos:\u00a0farmacia &hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-9954","page","type-page","status-publish","hentry","no-thumb"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/4dhealth.com\/es\/wp-json\/wp\/v2\/pages\/9954","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/4dhealth.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/4dhealth.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/4dhealth.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/4dhealth.com\/es\/wp-json\/wp\/v2\/comments?post=9954"}],"version-history":[{"count":26,"href":"https:\/\/4dhealth.com\/es\/wp-json\/wp\/v2\/pages\/9954\/revisions"}],"predecessor-version":[{"id":13224,"href":"https:\/\/4dhealth.com\/es\/wp-json\/wp\/v2\/pages\/9954\/revisions\/13224"}],"wp:attachment":[{"href":"https:\/\/4dhealth.com\/es\/wp-json\/wp\/v2\/media?parent=9954"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}