{"id":13265,"date":"2022-03-01T08:26:42","date_gmt":"2022-03-01T08:26:42","guid":{"rendered":"https:\/\/4dhealth.com\/?p=13265"},"modified":"2022-07-19T08:28:20","modified_gmt":"2022-07-19T08:28:20","slug":"premios-il3-ub-2","status":"publish","type":"post","link":"https:\/\/4dhealth.com\/es\/el-centro\/premios-il3-ub-2\/","title":{"rendered":"Recurso simulaci\u00f3n 4DH galardonado en los premios IL3-UB"},"content":{"rendered":"<p><strong><span class=\"Y2IQFc\" lang=\"es\">4D HEALTH DESARROLLA UN RECURSO DE SIMULACI\u00d3N GALARDONADO A LOS PREMIOS IL3-UB 2021<\/span><\/strong><\/p>\n<p style=\"text-align: justify;\"><span class=\"Y2IQFc\" lang=\"es\">El Instituto de Formaci\u00f3n Continua (IL3) y la Universidad de Barcelona entregaron el jueves 10 de febrero los Premios IL3-UB Francesc Santacana y Martorell y Joan Maria Malapeira y Gas a la innovaci\u00f3n en formaci\u00f3n continuada en t\u00edtulos propios 2021 en el marco de la Universidad de Barcelona, galardones de los cuales este a\u00f1o se ha celebrado su tercera edici\u00f3n.\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><span class=\"Y2IQFc\" lang=\"es\">El Premio Joan Maria Malapeira y Gas 2021, fue otorgado al equipo del M\u00e1ster en cuidados de enfermer\u00eda al enfermo cr\u00edtico IL3-UB, liderado por la Dra. M. Carmen Moreno, junto con su equipo conformado por el Dr. Miguel \u00c1ngel Hidalgo, Sr. Albert Gonz\u00e1lez y Sr. Jos\u00e9 Antonio Jerez por su presentaci\u00f3n \u201cLa Simulaci\u00f3n Virtual en UCI (SIMvirUCI): metodolog\u00eda innovadora potenciada por una pandemia\u201d.\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><span class=\"Y2IQFc\" lang=\"es\">El recurso educativo SIMvirUCI ha sido codesarrollado por el centro de innovaci\u00f3n y simulaci\u00f3n 4D Health y el M\u00e1ster en cuidados de enfermer\u00eda al enfermo cr\u00edtico IL3-UB. Se trata de un recurso educativo innovador, basado en la metodolog\u00eda de la simulaci\u00f3n cl\u00ednica, en modalidad virtual, que pretende contribuir al entrenamiento y capacitaci\u00f3n de los alumnos a trav\u00e9s del trabajo de casos cl\u00ednicos basados en la vida real, dentro del contexto de la Unidad de Cuidados Intensivos (UCI).\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><span class=\"Y2IQFc\" lang=\"es\">El uso de esta metodolog\u00eda de aprendizaje permite a los docentes desarrollar actividades dentro de sus estrategias educativas, e incorporarla en las modalidades did\u00e1cticas ya existentes (clases magistrales, seminarios, sesiones de simulaci\u00f3n, aula invertida, aprendizaje basado en problemas, etc.), con el prop\u00f3sito de fomentar en los estudiantes el aprendizaje reflexivo y basado en la experiencia.<\/span><\/p>\n<p style=\"text-align: justify;\"><span class=\"Y2IQFc\" lang=\"es\">El objetivo pedag\u00f3gico que se plantea con el uso de este recurso es ampliar el entorno de aprendizaje y fomentar el pensamiento cr\u00edtico, razonamiento cl\u00ednico y la toma de decisiones de los estudiantes mediante la visualizaci\u00f3n, an\u00e1lisis y reflexi\u00f3n de casos reales simulados, junto a sus docentes y facilitadores.\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><span class=\"Y2IQFc\" lang=\"es\">Los casos cl\u00ednicos desarrollados est\u00e1n relacionados con los cuidados enfermeros al enfermo cr\u00edtico con trastorno neurol\u00f3gico, politraum\u00e1tico, respiratorio, card\u00edaco y digestivo. A trav\u00e9s de su trabajo, los enfermeros\/as, pueden entrenar las competencias t\u00e9cnicas esenciales, junto con las competencias no t\u00e9cnicas tan necesarias en el \u00e1mbito sanitario como el trabajo en equipo, el liderazgo, la toma de decisiones, la comunicaci\u00f3n y la relaci\u00f3n con las nuevas tecnolog\u00edas.\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><span class=\"Y2IQFc\" lang=\"es\">El acto se llev\u00f3 a cabo en el Aula Capella del Edificio Hist\u00f3rico de la Universidad de Barcelona y fue presidido por el rector de la UB, el Dr. Joan Guardia, junto al director del IL3-UB, Guillem I\u00f1iguez, y la vicerrectora de Pol\u00edtica Acad\u00e9mica y Calidad de la UB, la Dra. Pilar Delgado.<\/span><\/p>\n<p style=\"text-align: justify;\"><span class=\"Y2IQFc\" lang=\"es\">Estos premios, de car\u00e1cter honor\u00edfico y periodicidad anual, son un reconocimiento al esfuerzo realizado para el desarrollo de personas y organizaciones mediante la innovaci\u00f3n en el marco de las titulaciones propias de posgrado y extensi\u00f3n universitaria de la Universidad de Barcelona. Valoran no s\u00f3lo la calidad de los proyectos, sino tambi\u00e9n su aplicabilidad pr\u00e1ctica.<\/span><\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-medium wp-image-12858\" src=\"https:\/\/4dhealth.com\/wp-content\/uploads\/2022\/03\/il31-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/4dhealth.com\/wp-content\/uploads\/2022\/03\/il31-300x225.jpg 300w, https:\/\/4dhealth.com\/wp-content\/uploads\/2022\/03\/il31-295x222.jpg 295w, https:\/\/4dhealth.com\/wp-content\/uploads\/2022\/03\/il31-768x576.jpg 768w, https:\/\/4dhealth.com\/wp-content\/uploads\/2022\/03\/il31-1024x768.jpg 1024w, https:\/\/4dhealth.com\/wp-content\/uploads\/2022\/03\/il31-418x313.jpg 418w, https:\/\/4dhealth.com\/wp-content\/uploads\/2022\/03\/il31.jpg 1055w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\u00a0 \u00a0 \u00a0<img decoding=\"async\" class=\"alignnone size-medium wp-image-13052\" src=\"https:\/\/4dhealth.com\/wp-content\/uploads\/2022\/04\/Imatge-Paciente-Cr\u00edtico-7-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/4dhealth.com\/wp-content\/uploads\/2022\/04\/Imatge-Paciente-Cr\u00edtico-7-300x225.jpg 300w, https:\/\/4dhealth.com\/wp-content\/uploads\/2022\/04\/Imatge-Paciente-Cr\u00edtico-7-295x222.jpg 295w, https:\/\/4dhealth.com\/wp-content\/uploads\/2022\/04\/Imatge-Paciente-Cr\u00edtico-7-768x576.jpg 768w, https:\/\/4dhealth.com\/wp-content\/uploads\/2022\/04\/Imatge-Paciente-Cr\u00edtico-7-1024x768.jpg 1024w, https:\/\/4dhealth.com\/wp-content\/uploads\/2022\/04\/Imatge-Paciente-Cr\u00edtico-7-418x314.jpg 418w, https:\/\/4dhealth.com\/wp-content\/uploads\/2022\/04\/Imatge-Paciente-Cr\u00edtico-7-1200x900.jpg 1200w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>4D HEALTH DESARROLLA UN RECURSO DE SIMULACI\u00d3N GALARDONADO A LOS PREMIOS IL3-UB 2021 El Instituto de Formaci\u00f3n Continua (IL3) y la Universidad de Barcelona entregaron el jueves 10 de febrero &hellip;<\/p>\n","protected":false},"author":1,"featured_media":12855,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[72,73],"tags":[],"class_list":["post-13265","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-el-centro","category-simulacion","has-thumb"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/4dhealth.com\/es\/wp-json\/wp\/v2\/posts\/13265","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/4dhealth.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/4dhealth.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/4dhealth.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/4dhealth.com\/es\/wp-json\/wp\/v2\/comments?post=13265"}],"version-history":[{"count":1,"href":"https:\/\/4dhealth.com\/es\/wp-json\/wp\/v2\/posts\/13265\/revisions"}],"predecessor-version":[{"id":13266,"href":"https:\/\/4dhealth.com\/es\/wp-json\/wp\/v2\/posts\/13265\/revisions\/13266"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/4dhealth.com\/es\/wp-json\/wp\/v2\/media\/12855"}],"wp:attachment":[{"href":"https:\/\/4dhealth.com\/es\/wp-json\/wp\/v2\/media?parent=13265"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/4dhealth.com\/es\/wp-json\/wp\/v2\/categories?post=13265"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/4dhealth.com\/es\/wp-json\/wp\/v2\/tags?post=13265"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}