{"id":13591,"date":"2022-11-14T15:17:37","date_gmt":"2022-11-14T15:17:37","guid":{"rendered":"https:\/\/4dhealth.com\/?p=13591"},"modified":"2022-11-14T15:18:34","modified_gmt":"2022-11-14T15:18:34","slug":"4d-health-presenta-un-recurso-educativo-en-la-jornada-de-simulacion-clinica-de-la-scartd","status":"publish","type":"post","link":"https:\/\/4dhealth.com\/es\/sin-categorizar\/4d-health-presenta-un-recurso-educativo-en-la-jornada-de-simulacion-clinica-de-la-scartd\/","title":{"rendered":"4D Health presenta en la jornada de Simulaci\u00f3n Cl\u00ednica de la SCARTD"},"content":{"rendered":"<p id=\"tw-target-text\" class=\"tw-data-text tw-text-large tw-ta\" dir=\"ltr\" style=\"text-align: justify;\" data-placeholder=\"Traducci\u00f3\"><span class=\"Y2IQFc\" lang=\"es\">El pasado 4 de noviembre se llev\u00f3 a cabo en el Auditorio de la Academia de las Ciencias M\u00e9dicas y de la Salud de Catalu\u00f1a y de Baleares las 4as Jornadas de Formaci\u00f3n Continua organizadas por la Societat Catalana Anestesiologia, Reanimaci\u00f3 i Terap\u00e8utica del Dolor (SCARTD). Este a\u00f1o se centraban en Simulaci\u00f3n Cl\u00ednica, donde la especialidad de Anestesiolog\u00eda juega un papel clave en el desarrollo de esta disciplina por su car\u00e1cter transversal en los hospitales, de amplio conocimiento de habilidades t\u00e9cnicas y situaciones cr\u00edticas; y por su liderazgo y capacidad en la toma de decisiones primordiales en la buena evoluci\u00f3n de los pacientes en muchos \u00e1mbitos, en la atenci\u00f3n segura y de calidad.<img decoding=\"async\" class=\"size-medium wp-image-13585 alignright\" src=\"https:\/\/4dhealth.com\/wp-content\/uploads\/2022\/11\/Jornades2-300x156.png\" alt=\"\" width=\"300\" height=\"156\" srcset=\"https:\/\/4dhealth.com\/wp-content\/uploads\/2022\/11\/Jornades2-300x156.png 300w, https:\/\/4dhealth.com\/wp-content\/uploads\/2022\/11\/Jornades2-768x400.png 768w, https:\/\/4dhealth.com\/wp-content\/uploads\/2022\/11\/Jornades2.png 1024w, https:\/\/4dhealth.com\/wp-content\/uploads\/2022\/11\/Jornades2-418x218.png 418w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <\/span><\/p>\n<p class=\"tw-data-text tw-text-large tw-ta\" dir=\"ltr\" style=\"text-align: justify;\" data-placeholder=\"Traducci\u00f3\"><span class=\"Y2IQFc\" lang=\"es\">Durante las Jornadas, el Dr. Marc Bausili, jefe de Servicio Anestesiolog\u00eda del Hospital Universitario M\u00fatua Terrassa y colaborador cl\u00ednico del centro de innovaci\u00f3n y simulaci\u00f3n 4D Health, present\u00f3 el proyecto de innovaci\u00f3n docente desarrollado por el centro igualadino sobre simulaci\u00f3n cl\u00ednica virtual en el enfermo cr\u00edtico, donde pudo explicar el trabajo desarrollado en modalidad virtual que fue incorporada por el M\u00e1ster de Cr\u00edticos de Enfermer\u00eda de la Universidad de Barcelona (IL3-UB), as\u00ed como de otros m\u00e1steres del pa\u00eds relacionados con la enfermer\u00eda del \u00e1mbito del paciente cr\u00edtico en la unidad de cuidados intensivos del pa\u00eds. <\/span><\/p>\n<p class=\"tw-data-text tw-text-large tw-ta\" dir=\"ltr\" style=\"text-align: justify;\" data-placeholder=\"Traducci\u00f3\"><span class=\"Y2IQFc\" lang=\"es\">Durante el 2021 el centro 4D Health configur\u00f3 un grupo de trabajo con expertos de enfermer\u00eda en enfermo cr\u00edtico del hospital de la Santa Creu y Sant Pau, coordinados por el Dr. Marc Bausili, y que fueron capaces de realizar casos de simulaci\u00f3n de alta complejidad y convertirlos en una herramienta docente de alta calidad y flexible en las diferentes necesidades del posgrado y \u00e1mbito de la formaci\u00f3n continuada.<\/span><\/p>\n<p id=\"tw-target-text\" class=\"tw-data-text tw-text-large tw-ta\" dir=\"ltr\" style=\"text-align: justify;\" data-placeholder=\"Traducci\u00f3\"><span class=\"Y2IQFc\" lang=\"es\">Los casos cl\u00ednicos desarrollados est\u00e1n relacionados con los cuidados enfermeros al enfermo cr\u00edtico con trastorno neurol\u00f3gico, politraum\u00e1tico, respiratorio, card\u00edaco y digestivo. A trav\u00e9s de su trabajo, los profesionales pueden entrenar las competencias t\u00e9cnicas esenciales, junto con las competencias no t\u00e9cnicas tan necesarias en el \u00e1mbito sanitario como el trabajo en equipo, el liderazgo, la toma de decisiones, la comunicaci\u00f3n y la relaci\u00f3n con las nuevas tecnolog\u00edas. <\/span><\/p>\n<p class=\"tw-data-text tw-text-large tw-ta\" dir=\"ltr\" style=\"text-align: justify;\" data-placeholder=\"Traducci\u00f3\"><span class=\"Y2IQFc\" lang=\"es\">El objetivo pedag\u00f3gico que se plantea con el uso de este recurso educativo de simulaci\u00f3n es ampliar el entorno de aprendizaje y fomentar el pensamiento cr\u00edtico y la toma de decisiones de los profesionales mediante la visualizaci\u00f3n, an\u00e1lisis y reflexi\u00f3n de casos reales simulados, junto con sus docentes y facilitadores, para posteriormente transferir estos conocimientos aprendidos a la pr\u00e1ctica asistencial real. <\/span><\/p>\n<p class=\"tw-data-text tw-text-large tw-ta\" dir=\"ltr\" style=\"text-align: justify;\" data-placeholder=\"Traducci\u00f3\"><span class=\"Y2IQFc\" lang=\"es\">Este proyecto de simulaci\u00f3n en el \u00e1mbito de cr\u00edticos ha sido galardonado con 2 premios. Primero recibi\u00f3 El Premio Joan Maria Malapeira y Gas 2021, de car\u00e1cter universitario, otorgado al equipo del M\u00e1ster en cuidados de enfermer\u00eda al enfermo cr\u00edtico IL3-UB. \u00daltimamente, tambi\u00e9n ha obtenido un nuevo premio internacional RECLA a las mejores pr\u00e1cticas en formaci\u00f3n continua en el XXVII Encuentro Internacional de la Red de Educaci\u00f3n Continua de LATAM y EUROPA.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El pasado 4 de noviembre se llev\u00f3 a cabo en el Auditorio de la Academia de las Ciencias M\u00e9dicas y de la Salud de Catalu\u00f1a y de Baleares las 4as &hellip;<\/p>\n","protected":false},"author":1,"featured_media":13582,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[74,72,73,60],"tags":[],"class_list":["post-13591","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad-medica","category-el-centro","category-simulacion","category-sin-categorizar","has-thumb"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/4dhealth.com\/es\/wp-json\/wp\/v2\/posts\/13591","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/4dhealth.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/4dhealth.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/4dhealth.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/4dhealth.com\/es\/wp-json\/wp\/v2\/comments?post=13591"}],"version-history":[{"count":2,"href":"https:\/\/4dhealth.com\/es\/wp-json\/wp\/v2\/posts\/13591\/revisions"}],"predecessor-version":[{"id":13593,"href":"https:\/\/4dhealth.com\/es\/wp-json\/wp\/v2\/posts\/13591\/revisions\/13593"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/4dhealth.com\/es\/wp-json\/wp\/v2\/media\/13582"}],"wp:attachment":[{"href":"https:\/\/4dhealth.com\/es\/wp-json\/wp\/v2\/media?parent=13591"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/4dhealth.com\/es\/wp-json\/wp\/v2\/categories?post=13591"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/4dhealth.com\/es\/wp-json\/wp\/v2\/tags?post=13591"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}